{"id":4706,"date":"2023-10-02T17:59:46","date_gmt":"2023-10-02T17:59:46","guid":{"rendered":"https:\/\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png"},"modified":"2023-10-02T17:59:46","modified_gmt":"2023-10-02T17:59:46","slug":"4-2","status":"inherit","type":"attachment","link":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/","title":{"rendered":"4"},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-4706","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 - Translators without Borders Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 - Translators without Borders Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Translators without Borders Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/translatorswithoutborders\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TranslatorsWB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/4-2\\\/\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/4-2\\\/\",\"name\":\"4 - Translators without Borders Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#website\"},\"datePublished\":\"2023-10-02T17:59:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/4-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/4-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/4-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/\",\"name\":\"Translators without Borders Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#organization\",\"name\":\"Translators without Borders\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/translatorswithoutborders.org\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/translatorswithoutborders.org\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1\",\"width\":248,\"height\":65,\"caption\":\"Translators without Borders\"},\"image\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/translatorswithoutborders\",\"https:\\\/\\\/x.com\\\/TranslatorsWB\",\"http:\\\/\\\/translatorswb\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/1500298\\\/?pathWildcard=1500298\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 - Translators without Borders Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/","og_locale":"es_ES","og_type":"article","og_title":"4 - Translators without Borders Blog","og_url":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/","og_site_name":"Translators without Borders Blog","article_publisher":"https:\/\/www.facebook.com\/translatorswithoutborders","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=1080%2C1080&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@TranslatorsWB","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/","url":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/","name":"4 - Translators without Borders Blog","isPartOf":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#website"},"datePublished":"2023-10-02T17:59:46+00:00","breadcrumb":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/translatorswithoutborders.org\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"4"}]},{"@type":"WebSite","@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#website","url":"https:\/\/translatorswithoutborders.org\/blog\/es\/","name":"Translators without Borders Blog","description":"","publisher":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/translatorswithoutborders.org\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#organization","name":"Translators without Borders","url":"https:\/\/translatorswithoutborders.org\/blog\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2017\/03\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1","contentUrl":"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2017\/03\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1","width":248,"height":65,"caption":"Translators without Borders"},"image":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/translatorswithoutborders","https:\/\/x.com\/TranslatorsWB","http:\/\/translatorswb","https:\/\/www.linkedin.com\/company-beta\/1500298\/?pathWildcard=1500298"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a8ykT2-1dU","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=768%2C768&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" data-attachment-id=\"4706\" data-permalink=\"https:\/\/translatorswithoutborders.org\/blog\/es\/4-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=1080%2C1080&amp;ssl=1\" data-orig-size=\"1080,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=300%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=840%2C840&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1080,"height":1080,"file":"2023\/10\/4.png","sizes":{"medium":{"file":"4-300x300.png","width":300,"height":300,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=300%2C300&ssl=1"},"large":{"file":"4-1024x1024.png","width":1024,"height":1024,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=840%2C840&ssl=1"},"thumbnail":{"file":"4-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=150%2C150&ssl=1"},"medium_large":{"file":"4-768x768.png","width":768,"height":768,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=768%2C768&ssl=1"},"sow-carousel-default":{"file":"4-272x182.png","width":272,"height":182,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?resize=272%2C182&ssl=1"},"full":{"file":"4.png?fit=1080%2C1080&ssl=1","width":1080,"height":1080,"mime_type":"image\/png","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png?fit=1080%2C1080&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/10\/4.png","_links":{"self":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/es\/wp-json\/wp\/v2\/media\/4706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/translatorswithoutborders.org\/blog\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/translatorswithoutborders.org\/blog\/es\/wp-json\/wp\/v2\/comments?post=4706"}]}}