{"id":4018,"date":"2023-02-21T14:28:10","date_gmt":"2023-02-21T14:28:10","guid":{"rendered":"https:\/\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2.jpeg"},"modified":"2023-02-21T14:28:10","modified_gmt":"2023-02-21T14:28:10","slug":"homepage2-2","status":"inherit","type":"attachment","link":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/","title":{"rendered":"homepage2"},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-4018","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>homepage2 - Translators without Borders Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"homepage2 - Translators without Borders Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Translators without Borders Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/translatorswithoutborders\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=2560%2C1435&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TranslatorsWB\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/homepage2-2\\\/\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/homepage2-2\\\/\",\"name\":\"homepage2 - Translators without Borders Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#website\"},\"datePublished\":\"2023-02-21T14:28:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/homepage2-2\\\/#breadcrumb\"},\"inLanguage\":\"ha\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/homepage2-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/homepage2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"homepage2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#website\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/\",\"name\":\"Translators without Borders Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ha\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#organization\",\"name\":\"Translators without Borders\",\"url\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ha\",\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/translatorswithoutborders.org\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/translatorswithoutborders.org\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1\",\"width\":248,\"height\":65,\"caption\":\"Translators without Borders\"},\"image\":{\"@id\":\"https:\\\/\\\/translatorswithoutborders.org\\\/blog\\\/ha\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/translatorswithoutborders\",\"https:\\\/\\\/x.com\\\/TranslatorsWB\",\"http:\\\/\\\/translatorswb\",\"https:\\\/\\\/www.linkedin.com\\\/company-beta\\\/1500298\\\/?pathWildcard=1500298\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"homepage2 - Translators without Borders Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/","og_locale":"en_US","og_type":"article","og_title":"homepage2 - Translators without Borders Blog","og_url":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/","og_site_name":"Translators without Borders Blog","article_publisher":"https:\/\/www.facebook.com\/translatorswithoutborders","og_image":[{"width":2560,"height":1435,"url":"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=2560%2C1435&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TranslatorsWB","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/","url":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/","name":"homepage2 - Translators without Borders Blog","isPartOf":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#website"},"datePublished":"2023-02-21T14:28:10+00:00","breadcrumb":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/#breadcrumb"},"inLanguage":"ha","potentialAction":[{"@type":"ReadAction","target":["https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/translatorswithoutborders.org\/blog\/ha\/"},{"@type":"ListItem","position":2,"name":"homepage2"}]},{"@type":"WebSite","@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#website","url":"https:\/\/translatorswithoutborders.org\/blog\/ha\/","name":"Translators without Borders Blog","description":"","publisher":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/translatorswithoutborders.org\/blog\/ha\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ha"},{"@type":"Organization","@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#organization","name":"Translators without Borders","url":"https:\/\/translatorswithoutborders.org\/blog\/ha\/","logo":{"@type":"ImageObject","inLanguage":"ha","@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2017\/03\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1","contentUrl":"https:\/\/i2.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2017\/03\/cropped-twblogo_3-1.png?fit=248%2C65&ssl=1","width":248,"height":65,"caption":"Translators without Borders"},"image":{"@id":"https:\/\/translatorswithoutborders.org\/blog\/ha\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/translatorswithoutborders","https:\/\/x.com\/TranslatorsWB","http:\/\/translatorswb","https:\/\/www.linkedin.com\/company-beta\/1500298\/?pathWildcard=1500298"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a8ykT2-12O","description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=300%2C168&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=1024%2C574&amp;ssl=1 1024w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=768%2C431&amp;ssl=1 768w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=1536%2C861&amp;ssl=1 1536w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=2048%2C1148&amp;ssl=1 2048w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=1200%2C673&amp;ssl=1 1200w, https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?w=1680&amp;ssl=1 1680w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" data-attachment-id=\"4018\" data-permalink=\"https:\/\/translatorswithoutborders.org\/blog\/ha\/homepage2-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=2560%2C1435&amp;ssl=1\" data-orig-size=\"2560,1435\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Claudia Mandal\\u00e0&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1674856999&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"homepage2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=300%2C168&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=840%2C471&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1435,"file":"2023\/02\/homepage2-scaled.jpeg","sizes":{"medium":{"file":"homepage2-300x168.jpeg","width":300,"height":168,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=300%2C168&ssl=1"},"large":{"file":"homepage2-1024x574.jpeg","width":1024,"height":574,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=840%2C471&ssl=1"},"thumbnail":{"file":"homepage2-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=150%2C150&ssl=1"},"medium_large":{"file":"homepage2-768x431.jpeg","width":768,"height":431,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=768%2C431&ssl=1"},"1536x1536":{"file":"homepage2-1536x861.jpeg","width":1536,"height":861,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=1536%2C861&ssl=1"},"2048x2048":{"file":"homepage2-2048x1148.jpeg","width":2048,"height":1148,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=2048%2C1148&ssl=1"},"post-thumbnail":{"file":"homepage2-1200x673.jpeg","width":1200,"height":673,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=1200%2C673&ssl=1"},"sow-carousel-default":{"file":"homepage2-272x182.jpeg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?resize=272%2C182&ssl=1"},"full":{"file":"homepage2-scaled.jpeg?fit=2560%2C1435&ssl=1","width":2560,"height":1435,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg?fit=2560%2C1435&ssl=1"}},"image_meta":{"aperture":"0","credit":"Claudia Mandal\u00e0","camera":"","caption":"","created_timestamp":"1674856999","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"homepage2.jpeg"},"post":null,"source_url":"https:\/\/translatorswithoutborders.org\/blog\/wp-content\/uploads\/2023\/02\/homepage2-scaled.jpeg","_links":{"self":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/ha\/wp-json\/wp\/v2\/media\/4018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/ha\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/translatorswithoutborders.org\/blog\/ha\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/translatorswithoutborders.org\/blog\/ha\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/translatorswithoutborders.org\/blog\/ha\/wp-json\/wp\/v2\/comments?post=4018"}]}}